{"id":75760,"date":"2022-04-07T18:59:13","date_gmt":"2022-04-07T18:59:13","guid":{"rendered":"https:\/\/gomotive.com\/company\/leadership\/"},"modified":"2026-05-11T12:49:57","modified_gmt":"2026-05-11T12:49:57","slug":"liderazgo","status":"publish","type":"page","link":"https:\/\/gomotive.com\/es-mx\/empresa\/liderazgo\/","title":{"rendered":"Liderazgo"},"content":{"rendered":"\n<section class=\"wp-block-motive-section has-gradient-dark-bottom-right-gradient-background has-background\" style=\"--md-section-height:initial;--sm-section-height:initial;--xs-section-height:initial;--desktop-margin-bottom:0;--desktop-margin-top:-65px;--tablet-margin-bottom:0;--tablet-margin-top:-65px;--mobile-margin-bottom:0;--mobile-margin-top:-65px;--z-index:1;has-parallex-effect:false\"><div class=\"container\">\n<div class=\"wp-block-liteberg-spacing-block custom-spacing\" style=\"min-height:140px;--md-section-height:140px;--sm-section-height:100px;--xs-section-height:100px\"><\/div>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text eyebrow-style has-phoenix-gray-6-color has-text-color has-link-color wp-elements-d7fa2cbbde414ea89fd1474e7780ad9e\" style=\"--tabletTextAlignment:center;--mobileTextAlignment:left;--desktopTextAlignment:center\">empresa<\/p>\n\n\n\n<div class=\"wp-block-liteberg-spacing-block custom-spacing\" style=\"min-height:20px;--md-section-height:20px;--sm-section-height:20px;--xs-section-height:20px\"><\/div>\n\n\n\n<h1 class=\"wp-block-liteberg-advanced-text has-x-large-font-size-style has-phoenix-white-color has-text-color has-link-color wp-elements-2cc90bb8056c5289f84290ca85b3f2b9\" style=\"--tabletTextAlignment:center;--mobileTextAlignment:left;--desktopTextAlignment:center\">Equipo de Liderazgo<\/h1>\n\n\n\n<div class=\"wp-block-liteberg-spacing-block custom-spacing\" style=\"min-height:16px;--md-section-height:16px;--sm-section-height:16px;--xs-section-height:16px\"><\/div>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text subtitle-style mx-auto has-phoenix-gray-5-color has-text-color has-link-color wp-elements-d41847ca85ddfae3198271a178d96fb6\" style=\"max-width:770px;--tabletTextAlignment:center;--mobileTextAlignment:left;--desktopTextAlignment:center\">El equipo directivo de Motive est\u00e1 comprometido con construir una empresa que desarrolla productos innovadores que los clientes valoran y con fomentar una cultura que impulsa a las personas a dar lo mejor de s\u00ed. Conoce a nuestros l\u00edderes a continuaci\u00f3n.<\/p>\n\n\n\n<div class=\"wp-block-liteberg-spacing-block custom-spacing\" style=\"min-height:160px;--md-section-height:160px;--sm-section-height:120px;--xs-section-height:100px\"><\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-motive-section has-background\" style=\"background-color:#f9f9f9;--md-section-height:initial;--sm-section-height:initial;--xs-section-height:initial;border:0px solid #000;--desktop-margin-bottom:0;--desktop-margin-top:-60px;--tablet-margin-bottom:0;--tablet-margin-top:-60px;--mobile-margin-bottom:0;--mobile-margin-top:-30px;--z-index:2;has-parallex-effect:false;--border-radius-top-left:60px;--border-radius-top-right:60px;--border-radius-bottom-left:0;--border-radius-bottom-right:0\">\n<div class=\"wp-block-liteberg-spacing-block custom-spacing\" style=\"min-height:60px;--md-section-height:60px;--sm-section-height:60px;--xs-section-height:30px\"><\/div>\n<\/section>\n\n\n\n<div class=\"wp-block-liteberg-leadership-grid has-background\" style=\"background-color:#f9f9f9\"><div class=\"container\">\n<h2 class=\"wp-block-heading group-heading\" id=\"h-equipo-directivo\">Equipo Directivo<\/h2>\n\n\n\n<div class=\"wp-block-group cards-wrapper is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2023\/03\/headshot-leader-shoaib-makani.png\" alt=\"headshot-leader-shoaib-makani\" loading=\"lazy\" fetchpriority=\"auto\" width=\"640\" height=\"640\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2023\/03\/headshot-leader-bw-shoaib-makani.png\" alt=\"headshot-leader-bw-shoaib-makani\" loading=\"lazy\" fetchpriority=\"auto\" width=\"640\" height=\"640\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-shoaib-makani\">Shoaib Makani<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Director Ejecutivo (CEO) y Cofundador<\/p>\n\n\n\n<p class=\"biography\">Shoaib fund\u00f3 Motive con la convicci\u00f3n de que la conectividad y la automatizaci\u00f3n pod\u00edan liberar el potencial de las empresas que impulsan la econom\u00eda f\u00edsica. Antes de fundar Motive, trabaj\u00f3 en Khosla Ventures, donde lider\u00f3 inversiones en compa\u00f1\u00edas de tecnolog\u00eda de consumo y empresarial. Previamente, dirigi\u00f3 el crecimiento internacional de AdMob. Su carrera comenz\u00f3 en Google, enfocado en gesti\u00f3n de producto y marketing. Es Licenciado en Gobierno y Econom\u00eda por la London School of Economics.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/05\/amish-color@2x.webp\" alt=\"amish-color@2x\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/05\/amish-bw@2x.webp\" alt=\"amish-bw@2x\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-amish-babu\">Amish Babu<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Director de Tecnolog\u00eda (CTO)<\/p>\n\n\n\n<p class=\"biography\">Amish lidera el \u00e1rea de tecnolog\u00eda e ingenier\u00eda en Motive. Antes de ser CTO, estuvo a cargo de los equipos de hardware y cadena de suministro, lanzando productos clave como AI Dashcam, AI Omnicam y Asset Gateway Mini. Antes de Motive, ocup\u00f3 cargos de liderazgo en Meta, Amazon y Square, donde contribuy\u00f3 al lanzamiento de productos como Oculus Quest, Amazon Kindle y Square Reader. Es Licenciado en Ingenier\u00eda Inform\u00e1tica y M\u00e1ster en Ciencia de Materiales por la Universidad de Stanford. Posee varias patentes en dise\u00f1o de hardware y sistemas.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/05\/hemant-color@2x.webp\" alt=\"hemant-color@2x\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/05\/hemant-bw@2x.webp\" alt=\"hemant-bw@2x\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-hemant-banavar\">Hemant Banavar<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Director de Producto (CPO)<\/p>\n\n\n\n<p class=\"biography\">Hemant dirige los equipos de producto, dise\u00f1o, an\u00e1lisis y ciencia de datos de la compa\u00f1\u00eda. Desde que se uni\u00f3 a Motive en 2019, ha ocupado roles de liderazgo en producto, ingenier\u00eda, an\u00e1lisis y salida al mercado, escalando productos existentes y lanzando nuevas soluciones al mercado. Fund\u00f3 y desarroll\u00f3 Motive Card, convirtiendo una idea en una l\u00ednea de productos de alto rendimiento en tiempo r\u00e9cord. Antes de Motive, ocup\u00f3 cargos de liderazgo en producto en Stripe, Uber, Yelp y Microsoft. Aporta m\u00e1s de 20 a\u00f1os de experiencia en la construcci\u00f3n y el escalamiento de productos innovadores en el sector tecnol\u00f3gico.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/03\/chirag-shah-chief-financial-officer1.webp\" alt=\"chirag-shah-chief-financial-officer(1)\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/03\/chirag-shah-chief-financial-officer.webp\" alt=\"chirag-shah-chief-financial-officer\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-chirag-shah\">Chirag Shah<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Director Financiero (CFO)<\/p>\n\n\n\n<p class=\"biography\">Chirag supervisa las funciones financieras de Motive, entre ellas, control interno, planificaci\u00f3n y an\u00e1lisis financiero, y finanzas estrat\u00e9gicas. Antes de Motive, fue CFO en Kong, empresa de software especializada en plataformas y servicios en la nube para gesti\u00f3n de API. Previamente, fue CFO en Cornerstone OnDemand, donde lider\u00f3 su exitosa salida a bolsa. Comenz\u00f3 su carrera como banquero de inversi\u00f3n enfocado en fusiones, adquisiciones y reestructuraciones. Es Licenciado en Finanzas por la Georgetown University y tiene un MBA por la Kellogg School of Management de Northwestern University.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/03\/patrick-richards-chief-information-officer.webp\" alt=\"patrick-richards-chief-information-officer\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/03\/patrick-richards-chief-information-officer1.webp\" alt=\"patrick-richards-chief-information-officer(1)\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-patrick-richards\">Patrick Richards<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Director de Informaci\u00f3n (CIO)<\/p>\n\n\n\n<p class=\"biography\">Patrick lidera la tecnolog\u00eda empresarial en Motive, que incluye TI, sistemas corporativos, inteligencia de negocios y seguridad de la informaci\u00f3n. Antes de Motive, fue Director de Gesti\u00f3n de Producto en Tableau Software, donde supervis\u00f3 el ciclo de vida del cliente y las transformaciones digitales. Previamente, fue Jefe de Integraciones con Socios en Amazon, liderando un equipo que gestionaba alianzas con empresas como Disney y la NFL. Patrick es Licenciado por la Universidad de Wisconsin Madison y tiene una Maestr\u00eda en Estrategia de la Informaci\u00f3n por la Columbia University..<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/12\/jiphun-satapathy-color-2x.webp\" alt=\"jiphun satapathy color 2x\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/12\/jiphun-satapathy-bw-2x.webp\" alt=\"jiphun satapathy bw 2x\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-jiphun-satapathy\">Jiphun Satapathy<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Director de Seguridad de la Informaci\u00f3n (CISO)<\/p>\n\n\n\n<p class=\"biography\">Jiphun lidera el \u00e1rea de Seguridad y Cumplimiento en Motive, donde supervisa la seguridad de productos, GRC (Gobierno, Riesgo y Cumplimiento), seguridad empresarial y productos de seguridad. Antes de unirse a Motive, se desempe\u00f1\u00f3 como Director de Seguridad de la Informaci\u00f3n en Medallia, liderando la estrategia de ciberseguridad, seguridad de productos, seguridad empresarial, GRC y operaciones de seguridad. Previamente, ocup\u00f3 cargos directivos en seguridad en Snowflake, AWS, Visa e Intel.<br><br>Jiphun aporta m\u00e1s de dos d\u00e9cadas de experiencia en la creaci\u00f3n y escalamiento de organizaciones de seguridad en empresas tecnol\u00f3gicas p\u00fablicas de alto crecimiento. Cuenta con una maestr\u00eda en Ciencias de la Computaci\u00f3n por la Universidad de Kentucky y posee m\u00faltiples patentes en materia de ciberseguridad.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/07\/Shu-White.webp\" alt=\"Shu White\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/03\/shulamite-white-chief-legal-officer-head-of-people1.webp\" alt=\"shulamite-white-chief-legal-officer-head-of-people(1)\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-shulamite-white\">Shulamite White<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Directora Legal y de Personas (CLO &amp; Head of People)<\/p>\n\n\n\n<p class=\"biography\">Shu lidera el \u00e1rea legal y de cumplimiento en Motive. Antes de unirse a la empresa, fue Vicepresidenta Senior y Consejera General en Imperva, empresa l\u00edder en ciberseguridad SaaS adquirida por Thoma Bravo por USD 2,100 millones en 2019. Previamente, trabaj\u00f3 nueve a\u00f1os en Fenwick &amp; West, asesorando a empresas tecnol\u00f3gicas en ofertas de capital y deuda, fusiones y adquisiciones, y cumplimiento corporativo. Sus clientes incluyeron Imperva, Shutterfly, Chegg, Fortinet, Concur, Responsys y Successfactors. Shu obtuvo su Doctorado en Derecho en UC Hastings College of the Law y es Licenciada en Artes por la New York University.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/05\/Thomas-Hansen-color.webp\" alt=\"Thomas-Hansen-color\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/05\/Thomas-Hansen-bw.webp\" alt=\"Thomas-Hansen-bw\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-thomas-hansen\">Thomas Hansen<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Presidente, Go-to-Market<\/p>\n\n\n\n<p class=\"biography\">Thomas lidera la organizaci\u00f3n global de comercializaci\u00f3n de Motive, que abarca ventas, marketing y funciones de atenci\u00f3n al cliente. Antes de unirse a Motive, Thomas se desempe\u00f1\u00f3 como Presidente de Amplitude, una plataforma p\u00fablica de an\u00e1lisis centrada en IA, donde dirigi\u00f3 la organizaci\u00f3n global de comercializaci\u00f3n de la empresa. Antes de Amplitude, fue Director de Ingresos en UiPath y Director de Operaciones en Carbon Black. Al inicio de su carrera, Thomas ocup\u00f3 puestos de liderazgo s\u00e9nior en Dropbox y Microsoft, incluido el cargo de Vicepresidente Global de SMB en Microsoft. Thomas tambi\u00e9n se desempe\u00f1a como Presidente de Dixa y ocupa cargos de asesor\u00eda e inversi\u00f3n en el ecosistema de IA, incluyendo RelationalAI, Forter, Artisanal Ventures y Evantic Capital. Obtuvo t\u00edtulos de licenciatura y maestr\u00eda en Econom\u00eda y Administraci\u00f3n de Empresas de Copenhagen Business School en Dinamarca.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading group-heading\" id=\"h-consejo-directivo\">Consejo directivo<\/h2>\n\n\n\n<div class=\"wp-block-group cards-wrapper is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/09\/meg-w-color.webp\" alt=\"meg-w-color\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/09\/meg-w-bw.webp\" alt=\"meg-w-bw\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-meg-whitman\">Meg Whitman<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Independiente<\/p>\n\n\n\n<p class=\"biography\">Meg Whitman es una l\u00edder empresarial y exembajadora de Estados Unidos en Kenia, con m\u00e1s de tres d\u00e9cadas de experiencia ejecutiva y en el sector p\u00fablico. Fue directora ejecutiva de eBay de 1998 a 2008, hasta convertirse en l\u00edder global de comercio electr\u00f3nico. De 2011 a 2015, fue presidenta y CEO de Hewlett-Packard, donde supervis\u00f3 su separaci\u00f3n en HP Inc. y Hewlett Packard Enterprise. Posteriormente, de 2015 a 2017, dirigi\u00f3 Hewlett Packard Enterprise como presidenta y CEO. Whitman ha formado parte de los consejos de administraci\u00f3n de Procter &amp; Gamble, General Motors y Dropbox, y recientemente se incorpor\u00f3 al consejo de administraci\u00f3n de CoreWeave, Inc.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/03\/dana-evan-independent.webp\" alt=\"dana-evan-independent\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/03\/dana-evan-independent1.webp\" alt=\"dana-evan-independent(1)\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-dana-evan\">Dana Evan<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Independiente<\/p>\n\n\n\n<p class=\"biography\">De 2013 a julio de 2020, Dana fue Venture Partner en Icon Ventures y, desde 2007, invirti\u00f3 y form\u00f3 parte de los consejos de compa\u00f1\u00edas de internet, tecnolog\u00eda y medios. Entre 1996 y 2007, fue Directora Financiera (CFO) de VeriSign, Inc. Actualmente, integra los consejos de Domo, Farfetch, Proofpoint y Momentive Global, y anteriormente de Criteo, Fusion-io, Omniture y Everyday Health. Es Licenciada en Comercio por la Santa Clara University y contadora p\u00fablica certificada (inactiva).<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/07\/ilya-color@2x.webp\" alt=\"ilya-color@2x\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/07\/ilya-bw@2x.webp\" alt=\"ilya-bw@2x\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-ilya-fushman\">Ilya Fushman<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Socio, Kleiner Perkins<\/p>\n\n\n\n<p class=\"biography\">Ilya Fushman es socio en Kleiner Perkins. Invierte en empresas en etapas tempranas y de crecimiento en software empresarial, servicios financieros y software de consumo. Ha invertido y participa en los consejos de compa\u00f1\u00edas como Rippling, Motive, Stord, Productboard, Loom y Cameo, adem\u00e1s de haber respaldado previamente a Slack e Intercom. Antes de Kleiner Perkins, fue socio en Index Ventures y lider\u00f3 el \u00e1rea de producto en Dropbox. Tiene un Doctorado en F\u00edsica Aplicada y una Maestr\u00eda en Ingenier\u00eda El\u00e9ctrica de Stanford, as\u00ed como una Licenciatura en F\u00edsica por Caltech.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/12\/adeyemi-ajao-color.webp\" alt=\"adeyemi-ajao-color\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/12\/adeyemi-ajao-bw.webp\" alt=\"adeyemi-ajao-bw\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-adeyemi-ajao\">Adeyemi Ajao<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Adeyemi Ajao Co-fundador y Managing Partner, Base10 Partners<\/p>\n\n\n\n<p class=\"biography\">Adeyemi Ajao es un emprendedor e inversionista en tecnolog\u00eda con un historial destacado en la creaci\u00f3n y escalamiento de empresas globales. Es co fundador y Managing Partner de Base10 Partners, y anteriormente fund\u00f3 Tuenti, adquirida por Telef\u00f3nica en 2010, y Identified, adquirida por Workday en 2014. En Workday, lanz\u00f3 Workday Ventures y se desempe\u00f1\u00f3 como Vicepresidente de Estrategia de Producto en Tecnolog\u00eda. Ajao ha sido uno de los primeros inversionistas en varias empresas de alto crecimiento, incluyendo Cabify. Cuenta con un MBA de la Escuela de Negocios de Posgrado de Stanford (Stanford Graduate School of Business) y fue incluido en la Lista Midas de Forbes en 2023 y 2024.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/03\/shoaib-makani-chief-executive-officer-co-founder.webp\" alt=\"shoaib-makani-chief-executive-officer-co-founder\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/03\/shoaib-makani-chief-executive-officer-co-founder-1.webp\" alt=\"shoaib-makani-chief-executive-officer-co-founder (1)\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-shoaib-makani-0\">Shoaib Makani<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Cofundador y CEO<\/p>\n\n\n\n<p class=\"biography\">Shoaib fund\u00f3 Motive con la convicci\u00f3n de que la conectividad y la automatizaci\u00f3n pod\u00edan liberar el potencial de las empresas que impulsan la econom\u00eda f\u00edsica. Antes de fundar Motive, trabaj\u00f3 en Khosla Ventures, donde lider\u00f3 inversiones en compa\u00f1\u00edas de tecnolog\u00eda de consumo y empresarial. Previamente, dirigi\u00f3 el crecimiento internacional de AdMob. Su carrera comenz\u00f3 en Google, enfocado en gesti\u00f3n de producto y marketing. Es Licenciado en Gobierno y Econom\u00eda por la London School of Economics.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/03\/alexander-niehenke-scale-ventures.webp\" alt=\"alexander-niehenke-scale-ventures\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/03\/alexander-niehenke-scale-ventures1.webp\" alt=\"alexander-niehenke-scale-ventures(1)\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-alexander-niehenke\">Alexander Niehenke<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Partner, Scale Ventures<\/p>\n\n\n\n<p class=\"biography\">Alex se uni\u00f3 a Scale en 2013 como Director y, desde 2017 es Socio. Se ha especializado en inversiones tempranas en software vertical. Ha invertido en Motive, Root Insurance, Scout RFP, Proxy, Spruce, Proscia y Archipelago. Motive ha sido una de las compa\u00f1\u00edas SaaS de m\u00e1s r\u00e1pido crecimiento. Scout RFP fue adquirida por Workday en 2019 por USD 540 millones y Root complet\u00f3 su IPO en 2020. Alex participa en los consejos de Motive, Proxy, Spruce, Proscia y Archipelago. Ha sido citado en TechCrunch, Business Insider, Forbes y Silicon Valley Business Journal.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/03\/aaron-schildkrout-investor.webp\" alt=\"aaron-schildkrout-investor\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/03\/aaron-schildkrout-investor1.webp\" alt=\"aaron-schildkrout-investor(1)\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-aaron-schildkrout\">Aaron Schildkrout<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Independiente<\/p>\n\n\n\n<p class=\"biography\">Aaron es miembro independiente del consejo de Motive y colabora con la compa\u00f1\u00eda desde 2018. Es miembro fundador del equipo de inversiones en Addition. Anteriormente, dirigi\u00f3 las \u00e1reas de Crecimiento, Datos y Producto de Conductores y Pasajeros en Uber, y antes fue fundador\/CEO de HowAboutWe (adquirida por IAC). Ha asesorado o invertido en empresas de alto crecimiento, como Noom, Ramp, Chainalysis, Brightwheel, Zap y The New York Times. Vive en Nueva York con su esposa (tambi\u00e9n fundadora\/CEO) y su hija.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-leadership-card card\">\n<figure class=\"wp-block-liteberg-image colored-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/03\/obaid-khan-independent.webp\" alt=\"obaid-khan-independent\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<figure class=\"wp-block-liteberg-image bw-headshot headshot\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2025\/03\/obaid-khan-independent1.webp\" alt=\"obaid-khan-independent(1)\" loading=\"lazy\" fetchpriority=\"auto\" width=\"562\" height=\"562\"\/><\/picture><\/figure>\n\n\n\n<h5 class=\"wp-block-heading name\" id=\"h-obaid-khan\">Obaid Khan<\/h5>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Cofundador y ex Director de Operaciones (COO)<\/p>\n\n\n\n<p class=\"biography\">Obaid es cofundador y ex Director de Operaciones (COO) de Motive, y actualmente forma parte de su consejo de administraci\u00f3n. Antes de fundar Motive, trabaj\u00f3 en asuntos legislativos para una organizaci\u00f3n sin fines de lucro en Washington DC. Es Licenciado por la University of California, San Diego.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-motive-modal modal fade\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"leadershipModal\" aria-hidden=\"true\" data-backdrop=\"true\" data-keyboard=\"true\" data-focus=\"true\" data-show=\"false\" id=\"leadershipModal\"><div class=\"modal-dialog modal-dialog-centered\" role=\"document\"><div class=\"modal-content\"><div class=\"modal-header\"><h3 class=\"modal-heading\">Bio<\/h3><button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\"><span aria-hidden=\"true\">\u00d7<\/span><\/button><\/div><div class=\"modal-body\">\n<figure class=\"wp-block-liteberg-image modal-image\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2022\/04\/placeholder_fm.png\" loading=\"lazy\" fetchpriority=\"auto\" width=\"\" height=\"\"\/><\/picture><\/figure>\n\n\n\n<div class=\"wp-block-group content is-layout-flow wp-block-group-is-layout-flow\">\n<h6 class=\"wp-block-liteberg-advanced-text h6-style modal-name\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\"><\/h6>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style modal-designation\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\"><\/p>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style modal-biography\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\"><\/p>\n<\/div>\n<\/div><div class=\"modal-footer\"><p class=\"disclaimer\"><\/p><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<section class=\"wp-block-motive-section has-background\" style=\"background-color:#010101;--md-section-height:initial;--sm-section-height:initial;--xs-section-height:initial;border:0px solid #000;--desktop-margin-bottom:0;--desktop-margin-top:-60px;--tablet-margin-bottom:0;--tablet-margin-top:-60px;--mobile-margin-bottom:0;--mobile-margin-top:-30px;--z-index:2;has-parallex-effect:false;--border-radius-top-left:60px;--border-radius-top-right:60px;--border-radius-bottom-left:0;--border-radius-bottom-right:0\">\n<div class=\"wp-block-liteberg-spacing-block custom-spacing\" style=\"min-height:60px;--md-section-height:60px;--sm-section-height:60px;--xs-section-height:30px\"><\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":0,"parent":45399,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"wp-custom-template-transparent-navigation-header-v2","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-75760","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Equipo Directivo y Consejo de Administraci\u00f3n de Motive<\/title>\n<meta name=\"description\" content=\"Conoce al equipo directivo y al consejo de administraci\u00f3n de Motive. L\u00edderes que impulsan la innovaci\u00f3n y el crecimiento en M\u00e9xico y el mundo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/pages\/75760\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liderazgo\" \/>\n<meta property=\"og:description\" content=\"Conoce al equipo directivo y al consejo de administraci\u00f3n de Motive. L\u00edderes que impulsan la innovaci\u00f3n y el crecimiento en M\u00e9xico y el mundo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gomotive.com\/es-mx\/empresa\/liderazgo\/\" \/>\n<meta property=\"og:site_name\" content=\"Motive\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GoMotive.Inc\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T12:49:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gomotive.com\/wp-content\/uploads\/2023\/03\/headshot-leader-shoaib-makani.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Motive_inc\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/empresa\\\/liderazgo\\\/\",\"url\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/empresa\\\/liderazgo\\\/\",\"name\":\"Equipo Directivo y Consejo de Administraci\u00f3n de Motive\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/empresa\\\/liderazgo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/empresa\\\/liderazgo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gomotive.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/headshot-leader-shoaib-makani.png\",\"datePublished\":\"2022-04-07T18:59:13+00:00\",\"dateModified\":\"2026-05-11T12:49:57+00:00\",\"description\":\"Conoce al equipo directivo y al consejo de administraci\u00f3n de Motive. L\u00edderes que impulsan la innovaci\u00f3n y el crecimiento en M\u00e9xico y el mundo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/empresa\\\/liderazgo\\\/#breadcrumb\"},\"inLanguage\":\"es-mx\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/empresa\\\/liderazgo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-mx\",\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/empresa\\\/liderazgo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gomotive.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/headshot-leader-shoaib-makani.png\",\"contentUrl\":\"https:\\\/\\\/gomotive.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/headshot-leader-shoaib-makani.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/empresa\\\/liderazgo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Company\",\"item\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/empresa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Liderazgo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/#website\",\"url\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/\",\"name\":\"Motive\",\"description\":\"Automated Operations Platform for the Physical Economy\",\"publisher\":{\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-mx\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/#organization\",\"name\":\"Motive\",\"url\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-mx\",\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gomotive.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Social-Share-Image.png\",\"contentUrl\":\"https:\\\/\\\/gomotive.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Social-Share-Image.png\",\"width\":2400,\"height\":1254,\"caption\":\"Motive\"},\"image\":{\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GoMotive.Inc\",\"https:\\\/\\\/x.com\\\/Motive_inc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/motive-inc\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Equipo Directivo y Consejo de Administraci\u00f3n de Motive","description":"Conoce al equipo directivo y al consejo de administraci\u00f3n de Motive. L\u00edderes que impulsan la innovaci\u00f3n y el crecimiento en M\u00e9xico y el mundo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/pages\/75760\/","og_locale":"es_MX","og_type":"article","og_title":"Liderazgo","og_description":"Conoce al equipo directivo y al consejo de administraci\u00f3n de Motive. L\u00edderes que impulsan la innovaci\u00f3n y el crecimiento en M\u00e9xico y el mundo.","og_url":"https:\/\/gomotive.com\/es-mx\/empresa\/liderazgo\/","og_site_name":"Motive","article_publisher":"https:\/\/www.facebook.com\/GoMotive.Inc","article_modified_time":"2026-05-11T12:49:57+00:00","og_image":[{"url":"https:\/\/gomotive.com\/wp-content\/uploads\/2023\/03\/headshot-leader-shoaib-makani.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Motive_inc","twitter_misc":{"Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gomotive.com\/es-mx\/empresa\/liderazgo\/","url":"https:\/\/gomotive.com\/es-mx\/empresa\/liderazgo\/","name":"Equipo Directivo y Consejo de Administraci\u00f3n de Motive","isPartOf":{"@id":"https:\/\/gomotive.com\/es-mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gomotive.com\/es-mx\/empresa\/liderazgo\/#primaryimage"},"image":{"@id":"https:\/\/gomotive.com\/es-mx\/empresa\/liderazgo\/#primaryimage"},"thumbnailUrl":"https:\/\/gomotive.com\/wp-content\/uploads\/2023\/03\/headshot-leader-shoaib-makani.png","datePublished":"2022-04-07T18:59:13+00:00","dateModified":"2026-05-11T12:49:57+00:00","description":"Conoce al equipo directivo y al consejo de administraci\u00f3n de Motive. L\u00edderes que impulsan la innovaci\u00f3n y el crecimiento en M\u00e9xico y el mundo.","breadcrumb":{"@id":"https:\/\/gomotive.com\/es-mx\/empresa\/liderazgo\/#breadcrumb"},"inLanguage":"es-mx","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gomotive.com\/es-mx\/empresa\/liderazgo\/"]}]},{"@type":"ImageObject","inLanguage":"es-mx","@id":"https:\/\/gomotive.com\/es-mx\/empresa\/liderazgo\/#primaryimage","url":"https:\/\/gomotive.com\/wp-content\/uploads\/2023\/03\/headshot-leader-shoaib-makani.png","contentUrl":"https:\/\/gomotive.com\/wp-content\/uploads\/2023\/03\/headshot-leader-shoaib-makani.png"},{"@type":"BreadcrumbList","@id":"https:\/\/gomotive.com\/es-mx\/empresa\/liderazgo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Company","item":"https:\/\/gomotive.com\/es-mx\/empresa\/"},{"@type":"ListItem","position":2,"name":"Liderazgo"}]},{"@type":"WebSite","@id":"https:\/\/gomotive.com\/es-mx\/#website","url":"https:\/\/gomotive.com\/es-mx\/","name":"Motive","description":"Automated Operations Platform for the Physical Economy","publisher":{"@id":"https:\/\/gomotive.com\/es-mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gomotive.com\/es-mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-mx"},{"@type":"Organization","@id":"https:\/\/gomotive.com\/es-mx\/#organization","name":"Motive","url":"https:\/\/gomotive.com\/es-mx\/","logo":{"@type":"ImageObject","inLanguage":"es-mx","@id":"https:\/\/gomotive.com\/es-mx\/#\/schema\/logo\/image\/","url":"https:\/\/gomotive.com\/wp-content\/uploads\/2022\/04\/Social-Share-Image.png","contentUrl":"https:\/\/gomotive.com\/wp-content\/uploads\/2022\/04\/Social-Share-Image.png","width":2400,"height":1254,"caption":"Motive"},"image":{"@id":"https:\/\/gomotive.com\/es-mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GoMotive.Inc","https:\/\/x.com\/Motive_inc","https:\/\/www.linkedin.com\/company\/motive-inc\/"]}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/gomotive.com\/es-mx\/empresa\/liderazgo\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"WebPage","headline":"Liderazgo","url":"http:\/\/gomotive.com\/es-mx\/empresa\/liderazgo\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/gomotive.com\/es-mx\/empresa\/liderazgo\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Uncategorized @es-mx","author":[{"@type":"Person","name":"Khawaja Waleed Iqbal"}],"creator":["Khawaja Waleed Iqbal"],"publisher":{"@type":"Organization","name":"Motive","logo":""},"keywords":[],"dateCreated":"2022-04-07T18:59:13Z","datePublished":"2022-04-07T18:59:13Z","dateModified":"2026-05-11T12:49:57Z"},"rendered":"<meta name=\"parsely-title\" content=\"Liderazgo\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/gomotive.com\/es-mx\/empresa\/liderazgo\/\" \/>\n<meta name=\"parsely-type\" content=\"index\" \/>\n<meta name=\"parsely-pub-date\" content=\"2022-04-07T18:59:13Z\" \/>\n<meta name=\"parsely-section\" content=\"Uncategorized @es-mx\" \/>\n<meta name=\"parsely-author\" content=\"Khawaja Waleed Iqbal\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/gomotive.com\/p.js"},"_links":{"self":[{"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/pages\/75760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/comments?post=75760"}],"version-history":[{"count":15,"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/pages\/75760\/revisions"}],"predecessor-version":[{"id":90203,"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/pages\/75760\/revisions\/90203"}],"up":[{"embeddable":true,"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/pages\/45399"}],"wp:attachment":[{"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/media?parent=75760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}