{"id":75756,"date":"2025-04-02T12:52:00","date_gmt":"2025-04-02T12:52:00","guid":{"rendered":"https:\/\/gomotive.com\/products\/dashcam\/"},"modified":"2026-06-29T15:58:40","modified_gmt":"2026-06-29T15:58:40","slug":"dashcam","status":"publish","type":"page","link":"https:\/\/gomotive.com\/es-mx\/productos\/dashcam\/","title":{"rendered":"IA Dashcam"},"content":{"rendered":"\n<style>\n.wp-block-liteberg-media-and-text li p {\n   color: inherit !important;\n}\n.wp-block-liteberg-bento-card.background-grad-bottom-right {\n   background: #0f0f0f !important;\n}\n.wp-block-liteberg-bento-card.swiper-slide { \n   height: auto;\n}\n@media (max-width: 767.98px) {\n    .wp-block-liteberg-bento-grid .container .cards-group.swiper .cards-grid.swiper-wrapper .wp-block-liteberg-bento-card:nth-child(4n+3) figure {\n        margin-top: -20px;\n    }\n}\n.wp-block-motive-announcement-bar {\n    display: none !important;\n}\n<\/style>\n\n\n\n<section class=\"wp-block-motive-section has-gradient-dark-bottom-right-gradient-background has-background\" style=\"--md-section-height:initial;--sm-section-height:initial;--xs-section-height:initial;--desktop-margin-bottom:0;--desktop-margin-top:-64px;--tablet-margin-bottom:0;--tablet-margin-top:-64px;--mobile-margin-bottom:0;--mobile-margin-top:-64px;--z-index:1;has-parallex-effect:false\">\n<div class=\"wp-block-liteberg-two-column-hero-v1 default has-phoenix-transparent-background-color has-background\">\n<div class=\"wp-block-group content-wrapper container is-horizontal is-content-justification-space-between is-layout-flex wp-container-core-group-is-layout-5e5b46d1 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group content-col col-12 col-sm-5 is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<h1 class=\"wp-block-liteberg-advanced-text eyebrow-style hero-eyebrow\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\"><mark style=\"background-color:#ffffff\" class=\"has-inline-color\">Nueva<\/mark>IA DASHCAM PARA FLOTAS<\/h1>\n\n\n\n<h2 class=\"wp-block-heading heading has-phoenix-white-color has-text-color\" id=\"h-ia-dashcam-plus\">IA Dashcam Plus.<\/h2>\n\n\n\n<p class=\"paragraph has-phoenix-white-color has-text-color\">Evita m\u00e1s accidentes y act\u00faa al instante con una IA precisa, comunicaci\u00f3n a manos libres y una fiabilidad superior en un solo dispositivo.<\/p>\n\n\n\n<div class=\"wp-block-group cta-group is-horizontal is-content-justification-flex-start is-layout-flex wp-block-group-is-layout-flex\">\n<span class=\"wp-block-motive-button gradient-btn has-anchor-link has-full-width-on-mobile cta-1\" gated-pdf-link=\"\"><a href=\"https:\/\/gomotive.com\/es-mx\/ponte-en-contacto\/\">Comienza ahora<\/a><\/span>\n\n\n\n<span class=\"wp-block-motive-button secondary-white-rounded has-anchor-link has-full-width-on-mobile cta-2\" gated-pdf-link=\"\"><a href=\"https:\/\/gomotive.com\/es-mx\/contacto-ventas\/\">Contacta a ventas<\/a><\/span>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group form-media-col col-12 col-sm-6 is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-phoenix-blocks-media has-border-radius hero-media\" style=\"transform:translateX(0)\">\n<div class=\"wp-block-phoenix-blocks-popup-video\" data-wistia-video-id=\"lwumotca0k\">\n<figure class=\"wp-block-video desktop-image\"><video autoplay loop muted src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/AIDC-Plus-Hero-Thumbnail.webm\" playsinline><\/video><\/figure>\n\n\n\n<p class=\"play-button\"><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-motive-section has-phoenix-black-background-color has-background\" style=\"--md-section-height:initial;--sm-section-height:initial;--xs-section-height:initial;border:0px solid #000;--desktop-margin-bottom:;--desktop-margin-top:-60px;--tablet-margin-bottom:0;--tablet-margin-top:-60px;--mobile-margin-bottom:0;--mobile-margin-top:-40px;--z-index:3;has-parallex-effect:false;--border-radius-top-left:40px;--border-radius-top-right:40px;--border-radius-bottom-left:40px;--border-radius-bottom-right:40px\">\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-liteberg-media-and-text dark-mode media-on-top-mobile has-phoenix-transparent-background-color has-background\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group text-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"eyebrow independent-eyebrow\">Procesador de IA precisa<\/p>\n\n\n\n<h3 class=\"wp-block-liteberg-advanced-text h3-style title\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Detecta m\u00e1s conductas peligrosas en tiempo real.<\/h3>\n\n\n\n<p class=\"description\">La AI Dashcam Plus puede ejecutar simult\u00e1neamente m\u00e1s de 30 modelos de IA precisa. El procesador Qualcomm Dragonwing\u2122 QCS6490 ofrece el triple de potencia de procesamiento que otras c\u00e1maras para tablero l\u00edderes en el mercado.<\/p>\n<\/div>\n\n\n\n<figure class=\"wp-block-liteberg-image media media-image\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Safety-Events-MX.webp\" alt=\"motive ai dashcam plus identifying safety events\" loading=\"lazy\" fetchpriority=\"auto\" width=\"1342\" height=\"900\"\/><\/picture><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-media-and-text dark-mode media-overflow media-on-left media-on-top-mobile has-phoenix-transparent-background-color has-background\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group text-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"eyebrow independent-eyebrow\">Visi\u00f3n est\u00e9reo<\/p>\n\n\n\n<h3 class=\"wp-block-liteberg-advanced-text h3-style title\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Evite colisiones por alcance y&nbsp;laterales.<\/h3>\n\n\n\n<p class=\"description\">Dos lentes de vista frontal ofrecen una percepci\u00f3n de profundidad superior que permite generar advertencias de colisi\u00f3n frontal y alertas de desv\u00edo de carril m\u00e1s precisas. <em>Disponible a finales de 2026<\/em>.<\/p>\n<\/div>\n\n\n\n<figure class=\"wp-block-liteberg-image media media-image\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Stereo-Vision.webp\" alt=\"motive ai dashcam plus two road facing lenses\" loading=\"lazy\" fetchpriority=\"auto\" width=\"1422\" height=\"820\"\/><\/picture><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-media-and-text dark-mode media-on-top-mobile has-phoenix-transparent-background-color has-background\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group text-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"eyebrow independent-eyebrow\">Reconocimiento autom\u00e1tico de placas de veh\u00edculos<\/p>\n\n\n\n<h3 class=\"wp-block-liteberg-advanced-text h3-style title\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Capture evidencia cr\u00edtica.<\/h3>\n\n\n\n<p class=\"description\">El lente de zoom de 1440p es compatible con el reconocimiento autom\u00e1tico de placas de veh\u00edculos y permite identificar con claridad los veh\u00edculos que se dan a la fuga tras una colisi\u00f3n, as\u00ed como los que participan en robos y otros incidentes. <em><em>Pr\u00f3ximamente<\/em><\/em>.<\/p>\n<\/div>\n\n\n\n<figure class=\"wp-block-liteberg-image media media-image\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/ALPR-MX-1.webp\" alt=\"license plate recognition with ai vision\" loading=\"lazy\" fetchpriority=\"auto\" width=\"1342\" height=\"900\"\/><\/picture><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-media-and-text dark-mode media-overflow media-on-left media-on-top-mobile has-phoenix-transparent-background-color has-background\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group text-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"eyebrow independent-eyebrow\">Llamadas bidireccionales en vivo<\/p>\n\n\n\n<h3 class=\"wp-block-liteberg-advanced-text h3-style title\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Con\u00e9ctate con los conductores al instante mediante comunicaci\u00f3n bidireccional en vivo.<\/h3>\n\n\n\n<p class=\"description\">Los supervisores podr\u00e1n llamar a los conductores para atender casos de fatiga, emergencias clim\u00e1ticas, mantenimiento y otros asuntos urgentes, sin que el conductor tenga que tocar su tel\u00e9fono.<\/p>\n\n\n\n<span class=\"wp-block-motive-button simple-white-btn mi-white-arrow-rounded has-anchor-link mi-arrow has-full-width-on-mobile\" gated-pdf-link=\"\"><a href=\"https:\/\/gomotive.com\/blog\/lamadas-bidireccionales-en-vivo-ai-dashcam-plus-mx\/\" type=\"link\" id=\"https:\/\/gomotive.com\/blog\/lamadas-bidireccionales-en-vivo-ai-dashcam-plus-mx\/\">Conoce mas<\/a><\/span>\n<\/div>\n\n\n\n<figure class=\"wp-block-liteberg-image media media-image\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Live-Two-Way-Calling.webp\" alt=\"truck driver using two way handsfree calling with dashcam\" loading=\"lazy\" fetchpriority=\"auto\" width=\"1422\" height=\"900\"\/><\/picture><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-media-and-text dark-mode media-on-top-mobile has-phoenix-transparent-background-color has-background\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group text-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"eyebrow independent-eyebrow\">Asistente<\/p>\n\n\n\n<h3 class=\"wp-block-liteberg-advanced-text h3-style title\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Resuelve dudas y toma acci\u00f3n con el asistente inteligente de Motive.<\/h3>\n\n\n\n<p class=\"description\">Los conductores pueden decir \u201cOye Atlas\u201d para guardar videos importantes, consultar cu\u00e1nto tiempo llevan conduciendo o encontrar la gasolinera m\u00e1s cercana sin distraerse. <em><em>Disponible a finales de 2026<\/em><\/em>.<\/p>\n<\/div>\n\n\n\n<figure class=\"wp-block-liteberg-image media media-image\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/AI-Voice-Assistant-MX.webp\" alt=\"driver using ai dashcam voice assistant to capture video\" loading=\"lazy\" fetchpriority=\"auto\" width=\"1342\" height=\"900\"\/><\/picture><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-media-and-text dark-mode media-on-left media-on-top-mobile has-phoenix-transparent-background-color has-background\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group text-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"eyebrow independent-eyebrow\">Automatizaciones<\/p>\n\n\n\n<h3 class=\"wp-block-liteberg-advanced-text h3-style title\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Solicita autom\u00e1ticamente a los conductores que corrijan las incidencias.<\/h3>\n\n\n\n<p class=\"description\">Los conductores recibir\u00e1n alertas para actuar ante c\u00f3digos de falla cr\u00edticos o reducir eventos innecesarios de inactividad, lo que mejora la seguridad y reduce los costos. <em>Pr\u00f3ximamente<\/em>.<\/p>\n<\/div>\n\n\n\n<figure class=\"wp-block-liteberg-image media media-image\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/AI-Automations-MX.webp\" alt=\"ai automation alerting driver of unnecessary idling\" loading=\"lazy\" fetchpriority=\"auto\" width=\"1342\" height=\"900\"\/><\/picture><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-motive-section has-gradient-dark-top-right-gradient-background has-background\" style=\"--md-section-height:initial;--sm-section-height:initial;--xs-section-height:initial;border:0px solid #000;--desktop-margin-bottom:0px;--desktop-margin-top:-60px;--tablet-margin-bottom:0;--tablet-margin-top:-60px;--mobile-margin-bottom:0;--mobile-margin-top:-60px;--z-index:2;has-parallex-effect:false;--border-radius-top-left:0;--border-radius-top-right:0;--border-radius-bottom-left:40px;--border-radius-bottom-right:40px\">\n<section class=\"wp-block-motive-section has-gradient-dark-top-right-gradient-background has-background\" style=\"--md-section-height:initial;--sm-section-height:initial;--xs-section-height:initial;border:0px solid #000;--desktop-margin-bottom:0;--desktop-margin-top:0px;--tablet-margin-bottom:0;--tablet-margin-top:0px;--mobile-margin-bottom:0;--mobile-margin-top:0px;--z-index:1;has-parallex-effect:false;--border-radius-top-left:0;--border-radius-top-right:0;--border-radius-bottom-left:0;--border-radius-bottom-right:0\">\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-liteberg-media-and-text dark-mode media-col-6 media-on-top-mobile has-phoenix-transparent-background-color has-background\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group text-container is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-liteberg-advanced-text h3-style title\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">M\u00e1xima confiabilidad en un solo dispositivo.<\/h3>\n\n\n\n<p class=\"description\">La IA Dashcam Plus combina el Vehicle Gateway y la IA Dashcam en un solo dispositivo, simplificando la instalaci\u00f3n y mejorando la confiabilidad.<\/p>\n\n\n\n<div class=\"wp-block-motive-list media-list\">\n<ul class=\"wp-block-list list\">\n<li>Su dise\u00f1o todo en uno reduce el tiempo de instalaci\u00f3n casi a la mitad, as\u00ed como los costos de mano de obra, y simplifica la gesti\u00f3n del hardware.<\/li>\n\n\n\n<li>El hardware integrado mejora la confiabilidad del dispositivo y asegura grabaciones cr\u00edticas,incluso si un cable se desconecta en una colisi\u00f3n grave.<\/li>\n\n\n\n<li><p>La conectividad Dual-SIM multi operador ofrece una cobertura LTE superior para un rastreo y carga de videos sin interrupciones. <em>Disponible a finales de 2026<\/em>.<\/p><\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-liteberg-image media media-image\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/AIDC-Plus-unified-device-MX.webp\" alt=\"all-in-one fleet hardware solution with aidc plus\" loading=\"lazy\" fetchpriority=\"auto\" width=\"1148\" height=\"1000\"\/><\/picture><\/figure>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<div class=\"wp-block-liteberg-bento-grid align-center\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group header-group is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"eyebrow\">ESPECIFICACIONES PRINCIPALES<\/p>\n\n\n\n<h2 class=\"wp-block-liteberg-advanced-text h2-style heading section-heading\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">IA de \u00faltima generaci\u00f3n. Hardware revolucionario.<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-group cta-group is-layout-flow wp-block-group-is-layout-flow\">\n<span class=\"wp-block-motive-button secondary-white-rounded-small has-anchor-link cta-1\" gated-pdf-link=\"\"><a href=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/03\/2025Q2_1209957876385891_Spec-Sheet_Dual-Facing-AI-Dashcam-Plus.pdf\" type=\"link\" id=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/03\/2025Q2_1209957876385891_Spec-Sheet_Dual-Facing-AI-Dashcam-Plus.pdf\">Consulta las especificaciones<\/a><\/span>\n\n\n\n<span class=\"wp-block-motive-button simple-white-btn mi-white-arrow-rounded has-anchor-link mi-arrow\" gated-pdf-link=\"\"><a href=\"https:\/\/gomotive.com\/es-mx\/ai-dash-cam-plus-instalacion\/\" type=\"link\" id=\"https:\/\/gomotive.com\/es-mx\/ai-dash-cam-plus-instalacion\/\">Consulta la gu\u00eda de instalaci\u00f3n<\/a><\/span>\n<\/div>\n\n\n\n<div class=\"wp-block-group cards-group swiper col-12 is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group cards-grid swiper-wrapper is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-liteberg-bento-card image-at-bottom background-grad-bottom-right swiper-slide\">\n<figure class=\"wp-block-liteberg-image card-image\"><picture><source media=\"(max-width: 767px)\" srcset=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Qualcomm-Chip-mobile.webp\"\/><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Qualcomm-Chip-desktop.webp\" alt=\"Qualcomm Dragonwing\u2122 QCS6490 processor image\" loading=\"lazy\" fetchpriority=\"auto\" width=\"520\" height=\"240\"\/><\/picture><\/figure>\n\n\n\n<div class=\"wp-block-group card-text-group is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<h3 class=\"wp-block-liteberg-advanced-text h3-style heading\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Procesador Qualcomm Dragonwing\u2122 QCS6490<\/h3>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style paragraph\" style=\"max-width:332px;--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Ofrece IA eficiente de alto rendimiento y un avanzado procesamiento de im\u00e1genes que posibilita una detecci\u00f3n precisa en tiempo real.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-bento-card image-at-top background-grad-bottom-right swiper-slide\">\n<figure class=\"wp-block-liteberg-image card-image\"><picture><source media=\"(min-width: 768px) and (max-width: 1023px)\" srcset=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Zoom-Lens-desktop-1.webp\"\/><source media=\"(max-width: 767px)\" srcset=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Zoom-Lens-mobile-1.webp\"\/><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Zoom-Lens-desktop-1.webp\" alt=\"1440p zoom lens closeup image - aidc plus\" loading=\"lazy\" fetchpriority=\"auto\" width=\"520\" height=\"240\"\/><\/picture><\/figure>\n\n\n\n<div class=\"wp-block-group card-text-group is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<h3 class=\"wp-block-liteberg-advanced-text h2-style heading\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Lente de zoom de 1440p<\/h3>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style paragraph\" style=\"max-width:440px;--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Un lente de zoom de alta resoluci\u00f3n con \u00e1ngulo de visi\u00f3n estrecho captura la informaci\u00f3n de un veh\u00edculo incluso si est\u00e1 a cierta distancia.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-bento-card image-at-bottom background-grad-bottom-right swiper-slide\">\n<figure class=\"wp-block-liteberg-image card-image\"><picture><source media=\"(max-width: 767px)\" srcset=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Speaker-Mic-mobile.webp\"\/><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Speaker-Mic-desktop.webp\" alt=\"noise-canceling audio highlights on dashcam\" loading=\"lazy\" fetchpriority=\"auto\" width=\"520\" height=\"306\"\/><\/picture><\/figure>\n\n\n\n<div class=\"wp-block-group card-text-group is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<h3 class=\"wp-block-liteberg-advanced-text h3-style heading\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Audio con cancelaci\u00f3n de&nbsp;ruido<\/h3>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style paragraph\" style=\"max-width:341px;--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">La bocina integrada y el micr\u00f3fono omnidireccional permiten conversaciones n\u00edtidas entre los conductores y la oficina, incluso en entornos ruidosos.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-bento-card image-at-top background-grad-bottom-right swiper-slide\">\n<figure class=\"wp-block-liteberg-image card-image\"><picture><source media=\"(max-width: 767px)\" srcset=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Dual-Band-GPS-mobile-1-1.webp\"\/><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Dual-Band-GPS-desktop-1-1.webp\" alt=\"dual-band gps in dashcam\" loading=\"lazy\" fetchpriority=\"auto\" width=\"520\" height=\"342\"\/><\/picture><\/figure>\n\n\n\n<div class=\"wp-block-group card-text-group is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<h3 class=\"wp-block-liteberg-advanced-text h2-style heading\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">GPS de doble banda<\/h3>\n\n\n\n<p class=\"wp-block-liteberg-advanced-text has-small-font-size-style paragraph\" style=\"max-width:422px;--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">El GPS de doble banda proporciona precisi\u00f3n a nivel de carril, mostrando exactamente en qu\u00e9 carril o calle se encuentra un veh\u00edculo, incluso en entornos urbanos densos.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group swiper-pagination is-horizontal is-layout-flex wp-block-group-is-layout-flex\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-motive-section has-background\" style=\"background-color:#f9f9f9;--md-section-height:initial;--sm-section-height:initial;--xs-section-height:initial;border:0px solid #000;--desktop-margin-bottom:0;--desktop-margin-top:-60px;--tablet-margin-bottom:0;--tablet-margin-top:-60px;--mobile-margin-bottom:0;--mobile-margin-top:-40px;--z-index:1;has-parallex-effect:false;--border-radius-top-left:0px;--border-radius-top-right:0px;--border-radius-bottom-left:40px;--border-radius-bottom-right:40px\">\n<div class=\"wp-block-liteberg-spacing-block custom-spacing\" style=\"min-height:80px;--md-section-height:60px;--sm-section-height:60px;--xs-section-height:40px\"><\/div>\n\n\n\n<div class=\"wp-block-liteberg-media-and-text media-on-left media-col-6 media-on-top-mobile\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group text-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"eyebrow independent-eyebrow\">BLOG<\/p>\n\n\n\n<h3 class=\"wp-block-liteberg-advanced-text h3-style title\" style=\"--tabletTextAlignment:left;--mobileTextAlignment:left;--desktopTextAlignment:left\">Presentamos la IA Dashcam&nbsp;Plus<\/h3>\n\n\n\n<p class=\"description\">Descubra c\u00f3mo este nuevo hardware y las funciones adicionales que se lanzar\u00e1n a lo largo de 2026 est\u00e1n ayudando a las organizaciones a detectar m\u00e1s riesgos, actuar con mayor rapidez y prevenir m\u00e1s accidentes.<\/p>\n\n\n\n<span class=\"wp-block-motive-button secondary-black-rounded-small has-anchor-link has-full-width-on-mobile\" gated-pdf-link=\"\"><a href=\"https:\/\/gomotive.com\/blog\/presentamos-ai-dashcam-plus-mx\/\">Leer ahora<\/a><\/span>\n<\/div>\n\n\n\n<figure class=\"wp-block-liteberg-image media media-image\"><picture><img decoding=\"async\" src=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Introducing-AIDC-Plus_e672db.webp\" alt=\"ai dashcam plus attached to windshield with driver image in rearview mirror\" loading=\"lazy\" fetchpriority=\"auto\" width=\"1148\" height=\"640\"\/><\/picture><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-spacing-block custom-spacing\" style=\"min-height:80px;--md-section-height:60px;--sm-section-height:60px;--xs-section-height:40px\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading container\" id=\"h-preguntas-frecuentes\">Preguntas frecuentes.<\/h2>\n\n\n\n<div class=\"wp-block-phoenix-blocks-spacer custom-spacing\" style=\"min-height:48px;--tablet-section-height:48px;--mobile-section-height:48px\"><\/div>\n\n\n\n<div class=\"wp-block-phoenix-blocks-accordion-set faqs container\">\n<div class=\"wp-block-phoenix-blocks-accordion-single-item\">\n<div class=\"wp-block-phoenix-blocks-accordion-header collapsed\">\n<h4 class=\"wp-block-heading heading\" id=\"h-que-es-la-ia-dashcam-plus-de-motive-y-en-que-se-diferencia-de-la-camara-de-tablero-comun-para-flotas\">\u00bfQu\u00e9 es la IA Dashcam Plus de Motive y en qu\u00e9 se diferencia de la c\u00e1mara de tablero com\u00fan para flotas?<\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-phoenix-blocks-accordion-body collapse\">\n<p>La IA Dashcam Plus de Motive re\u00fane capacidades de IA inigualables, comunicaci\u00f3n sin usar las manos y una confiabilidad superior en un dispositivo unificado. Trae toda la potencia de un procesador de IA Qualcomm de \u00faltima generaci\u00f3n con un poder de procesamiento tres veces mayor, por eso es capaz de ejecutar m\u00e1s de 30 modelos de IA para detectar los riesgos mientras ocurren.<\/p>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Adem\u00e1s, ofrece visi\u00f3n est\u00e9reo para una detecci\u00f3n m\u00e1s precisa de eventos, como advertencias de colisi\u00f3n frontal, desv\u00edo de carril y seguimiento cercano, junto con reconocimiento autom\u00e1tico de placas de veh\u00edculos, una funcionalidad muy \u00fatil para identificar veh\u00edculos que se dan a la fuga o que participan de robos u otros incidentes.<\/p>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La IA Dashcam Plus tambi\u00e9n incluye llamadas bidireccionales que permiten a los gerentes comunicarse con los conductores al instante, y un Asistente de Voz con IA integrado que ayuda a los conductores a obtener informaci\u00f3n sin necesidad de usar las manos. Y como combina la c\u00e1mara de tablero con Vehicle Gateway en un solo dispositivo, la IA Dashcam Plus brinda una fiabilidad superior y se instala en la mitad del tiempo.<\/p>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Ahora, las flotas pueden ver m\u00e1s, actuar m\u00e1s r\u00e1pido y prevenir una mayor cantidad de accidentes.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-phoenix-blocks-accordion-single-item\">\n<div class=\"wp-block-phoenix-blocks-accordion-header collapsed\">\n<h6 class=\"wp-block-heading heading\" id=\"h-que-tipo-de-eventos-de-conduccion-peligrosa-puede-detectar-y-grabar-la-ia-dashcam-plus\">\u00bfQu\u00e9 tipo de eventos de conducci\u00f3n peligrosa puede detectar y grabar la IA Dashcam Plus?<\/h6>\n<\/div>\n\n\n\n<div class=\"wp-block-phoenix-blocks-accordion-body collapse\">\n<p>La IA Dashcam Plus detecta y graba eventos como el uso de tel\u00e9fono celular, seguimiento cercano, advertencias de colisi\u00f3n frontal, cambios de carril peligrosos, violaciones de se\u00f1al de alto, violaciones de uso de cintur\u00f3n de seguridad y exceso de velocidad de la ruta, junto con otros comportamientos que se ir\u00e1n agregando a medida que entrenemos m\u00e1s modelos de IA. Estos eventos activan cargas de video y alertas para que los gerentes puedan investigar el caso y entrenar a los conductores de manera efectiva.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-phoenix-blocks-accordion-single-item\">\n<div class=\"wp-block-phoenix-blocks-accordion-header collapsed\">\n<h6 class=\"wp-block-heading heading\" id=\"h-sigo-necesitando-vehicle-gateway-con-la-ia-dashcam-plus\">\u00bfSigo necesitando Vehicle Gateway con la IA Dashcam Plus?<\/h6>\n<\/div>\n\n\n\n<div class=\"wp-block-phoenix-blocks-accordion-body collapse\">\n<p>No. La IA Dashcam Plus reemplaza la necesidad de un Vehicle Gateway independiente, lo que elimina el cableado adicional y reduce el tiempo de instalaci\u00f3n. Combina las funcionalidades de Seguridad Vial y Gesti\u00f3n de Flotas en un solo dispositivo.<\/p>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-phoenix-blocks-accordion-single-item\">\n<div class=\"wp-block-phoenix-blocks-accordion-header collapsed\">\n<h6 class=\"wp-block-heading heading\" id=\"h-como-se-realiza-la-instalacion-y-cuanto-demora\">\u00bfC\u00f3mo se realiza la instalaci\u00f3n y cu\u00e1nto demora?<\/h6>\n<\/div>\n\n\n\n<div class=\"wp-block-phoenix-blocks-accordion-body collapse\">\n<p>Normalmente, la IA Dashcam Plus se instala en menos de 15 minutos. El dispositivo se monta en el parabrisas y se conecta al veh\u00edculo a trav\u00e9s de un \u00fanico cable. Esto reduce el tiempo de inactividad y permite una instalaci\u00f3n mucho m\u00e1s sencilla en toda la flota.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-phoenix-blocks-accordion-single-item\">\n<div class=\"wp-block-phoenix-blocks-accordion-header collapsed\">\n<h6 class=\"wp-block-heading heading\" id=\"h-cuales-son-las-nuevas-funcionalidades-de-ia-y-seguridad-que-estaran-disponibles-en-la-ia-dashcam-plus\">\u00bfCu\u00e1les son las nuevas funcionalidades de IA y seguridad que estar\u00e1n disponibles en la IA Dashcam Plus?<\/h6>\n<\/div>\n\n\n\n<div class=\"wp-block-phoenix-blocks-accordion-body collapse\">\n<p>La IA Dashcam Plus ofrece capacidades de IA insuperables, comunicaci\u00f3n sin usar las manos y una fiabilidad superior.&nbsp;<\/p>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Las siguientes funcionalidades s\u00f3lo estar\u00e1n disponibles en la IA Dashcam Plus y se lanzar\u00e1n durante 2026.<\/p>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>M\u00e1s de 30 modelos de IA que se ejecutan al mismo tiempo.<\/li>\n\n\n\n<li>Reconocimiento autom\u00e1tico de placas de veh\u00edculos (ALPR).<\/li>\n\n\n\n<li>Visi\u00f3n est\u00e9reo que mejora la precisi\u00f3n de los modelos de IA.<\/li>\n\n\n\n<li>Tecnolog\u00eda Sensor Fusion para una detecci\u00f3n de eventos m\u00e1s precisa.<\/li>\n\n\n\n<li>Llamadas bidireccionales sin usar las manos.<\/li>\n\n\n\n<li>Asistente de Voz con IA.<\/li>\n\n\n\n<li>Ranura para doble SIM con m\u00e1s opciones de cobertura de datos celulares.<\/li>\n\n\n\n<li>Expandible a trav\u00e9s del Accessory Hub de Motive (hasta 10 puertos auxiliares).<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-liteberg-spacing-block custom-spacing\" style=\"min-height:80px;--md-section-height:60px;--sm-section-height:60px;--xs-section-height:40px\"><\/div>\n<\/section>\n\n\n\n<div class=\"wp-block-liteberg-conversion-module\"><div class=\"container\">\n<p class=\"eyebrow\">Cont\u00e1ctanos<\/p>\n\n\n\n<h2 class=\"wp-block-heading heading\" id=\"h-descubre-el-potencial-de-tus-operaciones-con-motive\">Descubre el potencial de tus operaciones con Motive.<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gestiona una flota m\u00e1s segura y eficiente.<\/li>\n\n\n\n<li>Mejora la visibilidad y automatiza tus operaciones.<\/li>\n\n\n\n<li>Identifica riesgos y automatiza el entrenamiento de operadores.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-group cta-wrapper is-layout-flow wp-block-group-is-layout-flow\">\n<span class=\"wp-block-motive-button gradient-btn has-anchor-link has-full-width-on-mobile\" gated-pdf-link=\"\"><a href=\"\/es-mx\/ponte-en-contacto\/\">Comienza ahora<\/a><\/span>\n\n\n\n<span class=\"wp-block-motive-button secondary-white-rounded has-anchor-link has-full-width-on-mobile\" gated-pdf-link=\"\"><a href=\"\/es-mx\/contacto-ventas\/\">Contacta a ventas<\/a><\/span>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":75748,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"wp-custom-template-transparent-navigation-header-v2","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-75756","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>IA Dashcam Plus - C\u00e1mara de tablero con IA para flotas en M\u00e9xico<\/title>\n<meta name=\"description\" content=\"La IA Dashcam Plus detecta conducci\u00f3n peligrosa en tiempo real con IA avanzada y video 1440p para prevenir colisiones y proteger tu flota.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/pages\/75756\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IA Dashcam\" \/>\n<meta property=\"og:description\" content=\"La IA Dashcam Plus detecta conducci\u00f3n peligrosa en tiempo real con IA avanzada y video 1440p para prevenir colisiones y proteger tu flota.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gomotive.com\/es-mx\/productos\/dashcam\/\" \/>\n<meta property=\"og:site_name\" content=\"Motive\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GoMotive.Inc\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T15:58:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Safety-Events-MX.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Motive_inc\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/productos\\\/dashcam\\\/\",\"url\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/productos\\\/dashcam\\\/\",\"name\":\"IA Dashcam Plus - C\u00e1mara de tablero con IA para flotas en M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/productos\\\/dashcam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/productos\\\/dashcam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gomotive.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Safety-Events-MX.webp\",\"datePublished\":\"2025-04-02T12:52:00+00:00\",\"dateModified\":\"2026-06-29T15:58:40+00:00\",\"description\":\"La IA Dashcam Plus detecta conducci\u00f3n peligrosa en tiempo real con IA avanzada y video 1440p para prevenir colisiones y proteger tu flota.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/productos\\\/dashcam\\\/#breadcrumb\"},\"inLanguage\":\"es-mx\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/productos\\\/dashcam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-mx\",\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/productos\\\/dashcam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gomotive.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Safety-Events-MX.webp\",\"contentUrl\":\"https:\\\/\\\/gomotive.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Safety-Events-MX.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/productos\\\/dashcam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Productos Motive \u2013 Soluciones de Hardware y Software en M\u00e9xico\",\"item\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IA Dashcam\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/#website\",\"url\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/\",\"name\":\"Motive\",\"description\":\"Automated Operations Platform for the Physical Economy\",\"publisher\":{\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-mx\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/#organization\",\"name\":\"Motive\",\"url\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-mx\",\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gomotive.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Social-Share-Image.png\",\"contentUrl\":\"https:\\\/\\\/gomotive.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Social-Share-Image.png\",\"width\":2400,\"height\":1254,\"caption\":\"Motive\"},\"image\":{\"@id\":\"https:\\\/\\\/gomotive.com\\\/es-mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GoMotive.Inc\",\"https:\\\/\\\/x.com\\\/Motive_inc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/motive-inc\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"IA Dashcam Plus - C\u00e1mara de tablero con IA para flotas en M\u00e9xico","description":"La IA Dashcam Plus detecta conducci\u00f3n peligrosa en tiempo real con IA avanzada y video 1440p para prevenir colisiones y proteger tu flota.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/pages\/75756\/","og_locale":"es_MX","og_type":"article","og_title":"IA Dashcam","og_description":"La IA Dashcam Plus detecta conducci\u00f3n peligrosa en tiempo real con IA avanzada y video 1440p para prevenir colisiones y proteger tu flota.","og_url":"https:\/\/gomotive.com\/es-mx\/productos\/dashcam\/","og_site_name":"Motive","article_publisher":"https:\/\/www.facebook.com\/GoMotive.Inc","article_modified_time":"2026-06-29T15:58:40+00:00","og_image":[{"url":"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Safety-Events-MX.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Motive_inc","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gomotive.com\/es-mx\/productos\/dashcam\/","url":"https:\/\/gomotive.com\/es-mx\/productos\/dashcam\/","name":"IA Dashcam Plus - C\u00e1mara de tablero con IA para flotas en M\u00e9xico","isPartOf":{"@id":"https:\/\/gomotive.com\/es-mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gomotive.com\/es-mx\/productos\/dashcam\/#primaryimage"},"image":{"@id":"https:\/\/gomotive.com\/es-mx\/productos\/dashcam\/#primaryimage"},"thumbnailUrl":"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Safety-Events-MX.webp","datePublished":"2025-04-02T12:52:00+00:00","dateModified":"2026-06-29T15:58:40+00:00","description":"La IA Dashcam Plus detecta conducci\u00f3n peligrosa en tiempo real con IA avanzada y video 1440p para prevenir colisiones y proteger tu flota.","breadcrumb":{"@id":"https:\/\/gomotive.com\/es-mx\/productos\/dashcam\/#breadcrumb"},"inLanguage":"es-mx","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gomotive.com\/es-mx\/productos\/dashcam\/"]}]},{"@type":"ImageObject","inLanguage":"es-mx","@id":"https:\/\/gomotive.com\/es-mx\/productos\/dashcam\/#primaryimage","url":"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Safety-Events-MX.webp","contentUrl":"https:\/\/gomotive.com\/wp-content\/uploads\/2026\/01\/Safety-Events-MX.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/gomotive.com\/es-mx\/productos\/dashcam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Productos Motive \u2013 Soluciones de Hardware y Software en M\u00e9xico","item":"https:\/\/gomotive.com\/es-mx\/productos\/"},{"@type":"ListItem","position":2,"name":"IA Dashcam"}]},{"@type":"WebSite","@id":"https:\/\/gomotive.com\/es-mx\/#website","url":"https:\/\/gomotive.com\/es-mx\/","name":"Motive","description":"Automated Operations Platform for the Physical Economy","publisher":{"@id":"https:\/\/gomotive.com\/es-mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gomotive.com\/es-mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-mx"},{"@type":"Organization","@id":"https:\/\/gomotive.com\/es-mx\/#organization","name":"Motive","url":"https:\/\/gomotive.com\/es-mx\/","logo":{"@type":"ImageObject","inLanguage":"es-mx","@id":"https:\/\/gomotive.com\/es-mx\/#\/schema\/logo\/image\/","url":"https:\/\/gomotive.com\/wp-content\/uploads\/2022\/04\/Social-Share-Image.png","contentUrl":"https:\/\/gomotive.com\/wp-content\/uploads\/2022\/04\/Social-Share-Image.png","width":2400,"height":1254,"caption":"Motive"},"image":{"@id":"https:\/\/gomotive.com\/es-mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GoMotive.Inc","https:\/\/x.com\/Motive_inc","https:\/\/www.linkedin.com\/company\/motive-inc\/"]}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/gomotive.com\/es-mx\/productos\/dashcam\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"WebPage","headline":"IA Dashcam","url":"http:\/\/gomotive.com\/es-mx\/productos\/dashcam\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/gomotive.com\/es-mx\/productos\/dashcam\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Uncategorized @es-mx","author":[{"@type":"Person","name":"Rafah Mehfooz"}],"creator":["Rafah Mehfooz"],"publisher":{"@type":"Organization","name":"Motive","logo":""},"keywords":[],"dateCreated":"2025-04-02T12:52:00Z","datePublished":"2025-04-02T12:52:00Z","dateModified":"2026-06-29T15:58:40Z"},"rendered":"<meta name=\"parsely-title\" content=\"IA Dashcam\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/gomotive.com\/es-mx\/productos\/dashcam\/\" \/>\n<meta name=\"parsely-type\" content=\"index\" \/>\n<meta name=\"parsely-pub-date\" content=\"2025-04-02T12:52:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Uncategorized @es-mx\" \/>\n<meta name=\"parsely-author\" content=\"Rafah Mehfooz\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/gomotive.com\/p.js"},"_links":{"self":[{"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/pages\/75756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/comments?post=75756"}],"version-history":[{"count":19,"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/pages\/75756\/revisions"}],"predecessor-version":[{"id":92967,"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/pages\/75756\/revisions\/92967"}],"up":[{"embeddable":true,"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/pages\/75748"}],"wp:attachment":[{"href":"https:\/\/gomotive.com\/es-mx\/wp-json\/wp\/v2\/media?parent=75756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}